{"id":2004,"date":"2024-09-14T06:54:09","date_gmt":"2024-09-14T05:54:09","guid":{"rendered":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004"},"modified":"2024-10-22T18:52:56","modified_gmt":"2024-10-22T17:52:56","slug":"regalo-della-grecia","status":"publish","type":"post","link":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004","title":{"rendered":"Regalo della Grecia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mercoled\u00ec 11 settembre golfo di\u00a0 Vorios Evvoikos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nell&#8217;ultimo tratto di mare, prima di arrivare in cantiere a Limni. Enrico grida: &#8220;Corri corri Lella, guarda l\u00e0&#8221;. Dalla\u00a0 prua di Felicit\u00e0, molto lontano, davanti a noi, si vedono spuntare dall&#8217;acqua delle piccole pinne scure, potrebbero essere dei delfini da come si muovono,\u00a0 siamo troppo lontani\u00a0 per esserne certi, si dirigono verso est. Comunque torno in dinette a prendere il telefonino per\u00a0 delle foto. Non cambiamo rotta per seguirli, non acceleriamo l&#8217;andatura per raggiungerli, l\u00ec osserviamo da lontano gi\u00e0 felici di averli avvistati, anche se in Grecia non \u00e8 raro vederli, a noi, erano un po&#8217; che\u00a0 non capitava pi\u00f9. &#8220;Guarda guarda, hanno cambiato direzione, ci vengono incontro&#8221;, ora che si stanno avvicinando \u00e8\u00a0 chiaro che siano un banco di delfini, arrivano alla spicciolata, prima uno grande che ci si affianca, poi altri due che si immergono davanti alla prua, quelli che arrivano dopo\u00a0 li sormontano, e loro\u00a0risalgono e fanno gruppo con altri, li conto, sembrano\u00a0 sei o poco pi\u00f9, stanno giocando con la prua di Felicit\u00e0, ci accompagnano e si divertono in un continuo scambio di posizioni, fuori e dentro l&#8217; acqua, a destra e a sinistra sempre\u00a0 della prua,\u00a0 nuotano veloci e felici con una leggerezza incredibile, sembrano volare in acqua. Il mare \u00e8 calmo e la luce del mezzogiorno ce ne permette una visuale perfetta, siamo affascinati e anche noi felici, come se ci avessero contagiati. Aggrappata alla battagliola ho la testa protesa verso di loro, Enrico sta filmando ed entrambi\u00a0 non abbiamo che poche parole, \u00e8\u00a0 un contino esclamare: &#8220;Guarda guarda guarda, ma che belli&#8221;,\u00a0 uno di loro si struscia sulla barca, sono eleganti, armoniosi. Sono rimasti con noi un paio di minuti, poi all&#8217;improvviso se ne sono andati, meno il pi\u00f9 grande che \u00e8 restato con noi ancora un po&#8217;, due minuti emozionanti, un ultimo regalo della Grecia e del suo splendido mare. Oppure un arrivederci all&#8217;anno prossimo.<\/p>\n","protected":false},"excerpt":{"rendered":"Mercoled\u00ec 11 settembre golfo di\u00a0 Vorios Evvoikos. Nell&#8217;ultimo tratto di mare, prima di arrivare in cantiere a Limni. Enrico grida: &#8220;Corri corri Lella, guarda l\u00e0&#8221;. Dalla\u00a0 prua di Felicit\u00e0, molto lontano, davanti a noi, si vedono spuntare dall&#8217;acqua delle piccole pinne scure, potrebbero essere dei delfini da come si muovono,\u00a0 siamo troppo lontani\u00a0 per esserne <a href=\"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004\" class=\"more-link\">&#8230;continua a leggere<span class=\"screen-reader-text\"> &#8220;Regalo della Grecia&#8221;<\/span><\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-2004","post","type-post","status-publish","format-standard","category-libri","h-entry","hentry","h-as-article"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Mercoled\u00ec 11 settembre golfo di Vorios Evvoikos. Nell&#039;ultimo tratto di mare, prima di arrivare in cantiere a Limni. Enrico grida: &quot;Corri corri Lella, guarda l\u00e0&quot;. Dalla prua di Felicit\u00e0, molto lontano, davanti a noi, si vedono spuntare dall&#039;acqua delle piccole pinne scure, potrebbero essere dei delfini da come si muovono, siamo troppo lontani per esserne\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Lella Mascia Leoni | Scrivo perch\u00e9 mi piace!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Regalo della Grecia | Lella Mascia Leoni\" \/>\n\t\t<meta property=\"og:description\" content=\"Mercoled\u00ec 11 settembre golfo di Vorios Evvoikos. Nell&#039;ultimo tratto di mare, prima di arrivare in cantiere a Limni. Enrico grida: &quot;Corri corri Lella, guarda l\u00e0&quot;. Dalla prua di Felicit\u00e0, molto lontano, davanti a noi, si vedono spuntare dall&#039;acqua delle piccole pinne scure, potrebbero essere dei delfini da come si muovono, siamo troppo lontani per esserne\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-09-14T05:54:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-10-22T17:52:56+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Regalo della Grecia | Lella Mascia Leoni\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Mercoled\u00ec 11 settembre golfo di Vorios Evvoikos. Nell&#039;ultimo tratto di mare, prima di arrivare in cantiere a Limni. Enrico grida: &quot;Corri corri Lella, guarda l\u00e0&quot;. Dalla prua di Felicit\u00e0, molto lontano, davanti a noi, si vedono spuntare dall&#039;acqua delle piccole pinne scure, potrebbero essere dei delfini da come si muovono, siamo troppo lontani per esserne\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/2024\\\/09\\\/14\\\/regalo-della-grecia\\\/2004#article\",\"name\":\"Regalo della Grecia | Lella Mascia Leoni\",\"headline\":\"Regalo della Grecia\",\"author\":{\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/author\\\/admin#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/2024\\\/09\\\/14\\\/regalo-della-grecia\\\/2004#articleImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/453eea83ba7fc7c9355e275a0c2a9e539a2b16fb999d06e001c610b5de6bb099?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"},\"datePublished\":\"2024-09-14T06:54:09+01:00\",\"dateModified\":\"2024-10-22T18:52:56+01:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/2024\\\/09\\\/14\\\/regalo-della-grecia\\\/2004#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/2024\\\/09\\\/14\\\/regalo-della-grecia\\\/2004#webpage\"},\"articleSection\":\"Libri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/2024\\\/09\\\/14\\\/regalo-della-grecia\\\/2004#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mascialeoni.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/category\\\/libri#listItem\",\"name\":\"Libri\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/category\\\/libri#listItem\",\"position\":2,\"name\":\"Libri\",\"item\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/category\\\/libri\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/2024\\\/09\\\/14\\\/regalo-della-grecia\\\/2004#listItem\",\"name\":\"Regalo della Grecia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/2024\\\/09\\\/14\\\/regalo-della-grecia\\\/2004#listItem\",\"position\":3,\"name\":\"Regalo della Grecia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/category\\\/libri#listItem\",\"name\":\"Libri\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/#person\",\"name\":\"Lella\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/2024\\\/09\\\/14\\\/regalo-della-grecia\\\/2004#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/686f365631b38b9a6f85cc82d3dd3f5fc20e10812ecfadd88ad4618dde9cebce?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Lella\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/author\\\/admin#author\",\"url\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/author\\\/admin\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/2024\\\/09\\\/14\\\/regalo-della-grecia\\\/2004#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/453eea83ba7fc7c9355e275a0c2a9e539a2b16fb999d06e001c610b5de6bb099?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/2024\\\/09\\\/14\\\/regalo-della-grecia\\\/2004#webpage\",\"url\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/2024\\\/09\\\/14\\\/regalo-della-grecia\\\/2004\",\"name\":\"Regalo della Grecia | Lella Mascia Leoni\",\"description\":\"Mercoled\\u00ec 11 settembre golfo di Vorios Evvoikos. Nell'ultimo tratto di mare, prima di arrivare in cantiere a Limni. Enrico grida: \\\"Corri corri Lella, guarda l\\u00e0\\\". Dalla prua di Felicit\\u00e0, molto lontano, davanti a noi, si vedono spuntare dall'acqua delle piccole pinne scure, potrebbero essere dei delfini da come si muovono, siamo troppo lontani per esserne\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/2024\\\/09\\\/14\\\/regalo-della-grecia\\\/2004#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/author\\\/admin#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/index.php\\\/author\\\/admin#author\"},\"datePublished\":\"2024-09-14T06:54:09+01:00\",\"dateModified\":\"2024-10-22T18:52:56+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/#website\",\"url\":\"https:\\\/\\\/www.mascialeoni.com\\\/\",\"name\":\"Lella Mascia Leoni\",\"description\":\"Scrivo perch\\u00e9 mi piace!\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mascialeoni.com\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Regalo della Grecia | Lella Mascia Leoni","description":"Mercoled\u00ec 11 settembre golfo di Vorios Evvoikos. Nell'ultimo tratto di mare, prima di arrivare in cantiere a Limni. Enrico grida: \"Corri corri Lella, guarda l\u00e0\". Dalla prua di Felicit\u00e0, molto lontano, davanti a noi, si vedono spuntare dall'acqua delle piccole pinne scure, potrebbero essere dei delfini da come si muovono, siamo troppo lontani per esserne","canonical_url":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004#article","name":"Regalo della Grecia | Lella Mascia Leoni","headline":"Regalo della Grecia","author":{"@id":"https:\/\/www.mascialeoni.com\/index.php\/author\/admin#author"},"publisher":{"@id":"https:\/\/www.mascialeoni.com\/#person"},"image":{"@type":"ImageObject","@id":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004#articleImage","url":"https:\/\/secure.gravatar.com\/avatar\/453eea83ba7fc7c9355e275a0c2a9e539a2b16fb999d06e001c610b5de6bb099?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"},"datePublished":"2024-09-14T06:54:09+01:00","dateModified":"2024-10-22T18:52:56+01:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004#webpage"},"isPartOf":{"@id":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004#webpage"},"articleSection":"Libri"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.mascialeoni.com#listItem","position":1,"name":"Home","item":"https:\/\/www.mascialeoni.com","nextItem":{"@type":"ListItem","@id":"https:\/\/www.mascialeoni.com\/index.php\/category\/libri#listItem","name":"Libri"}},{"@type":"ListItem","@id":"https:\/\/www.mascialeoni.com\/index.php\/category\/libri#listItem","position":2,"name":"Libri","item":"https:\/\/www.mascialeoni.com\/index.php\/category\/libri","nextItem":{"@type":"ListItem","@id":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004#listItem","name":"Regalo della Grecia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.mascialeoni.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004#listItem","position":3,"name":"Regalo della Grecia","previousItem":{"@type":"ListItem","@id":"https:\/\/www.mascialeoni.com\/index.php\/category\/libri#listItem","name":"Libri"}}]},{"@type":"Person","@id":"https:\/\/www.mascialeoni.com\/#person","name":"Lella","image":{"@type":"ImageObject","@id":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/686f365631b38b9a6f85cc82d3dd3f5fc20e10812ecfadd88ad4618dde9cebce?s=96&d=mm&r=g","width":96,"height":96,"caption":"Lella"}},{"@type":"Person","@id":"https:\/\/www.mascialeoni.com\/index.php\/author\/admin#author","url":"https:\/\/www.mascialeoni.com\/index.php\/author\/admin","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/453eea83ba7fc7c9355e275a0c2a9e539a2b16fb999d06e001c610b5de6bb099?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004#webpage","url":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004","name":"Regalo della Grecia | Lella Mascia Leoni","description":"Mercoled\u00ec 11 settembre golfo di Vorios Evvoikos. Nell'ultimo tratto di mare, prima di arrivare in cantiere a Limni. Enrico grida: \"Corri corri Lella, guarda l\u00e0\". Dalla prua di Felicit\u00e0, molto lontano, davanti a noi, si vedono spuntare dall'acqua delle piccole pinne scure, potrebbero essere dei delfini da come si muovono, siamo troppo lontani per esserne","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.mascialeoni.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004#breadcrumblist"},"author":{"@id":"https:\/\/www.mascialeoni.com\/index.php\/author\/admin#author"},"creator":{"@id":"https:\/\/www.mascialeoni.com\/index.php\/author\/admin#author"},"datePublished":"2024-09-14T06:54:09+01:00","dateModified":"2024-10-22T18:52:56+01:00"},{"@type":"WebSite","@id":"https:\/\/www.mascialeoni.com\/#website","url":"https:\/\/www.mascialeoni.com\/","name":"Lella Mascia Leoni","description":"Scrivo perch\u00e9 mi piace!","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.mascialeoni.com\/#person"}}]},"og:locale":"it_IT","og:site_name":"Lella Mascia Leoni | Scrivo perch\u00e9 mi piace!","og:type":"article","og:title":"Regalo della Grecia | Lella Mascia Leoni","og:description":"Mercoled\u00ec 11 settembre golfo di Vorios Evvoikos. Nell'ultimo tratto di mare, prima di arrivare in cantiere a Limni. Enrico grida: &quot;Corri corri Lella, guarda l\u00e0&quot;. Dalla prua di Felicit\u00e0, molto lontano, davanti a noi, si vedono spuntare dall'acqua delle piccole pinne scure, potrebbero essere dei delfini da come si muovono, siamo troppo lontani per esserne","og:url":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004","article:published_time":"2024-09-14T05:54:09+00:00","article:modified_time":"2024-10-22T17:52:56+00:00","twitter:card":"summary","twitter:title":"Regalo della Grecia | Lella Mascia Leoni","twitter:description":"Mercoled\u00ec 11 settembre golfo di Vorios Evvoikos. Nell'ultimo tratto di mare, prima di arrivare in cantiere a Limni. Enrico grida: &quot;Corri corri Lella, guarda l\u00e0&quot;. Dalla prua di Felicit\u00e0, molto lontano, davanti a noi, si vedono spuntare dall'acqua delle piccole pinne scure, potrebbero essere dei delfini da come si muovono, siamo troppo lontani per esserne"},"aioseo_meta_data":{"post_id":"2004","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-09-14 05:54:29","updated":"2025-06-03 19:56:06","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.mascialeoni.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.mascialeoni.com\/index.php\/category\/libri\" title=\"Libri\">Libri<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRegalo della Grecia\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.mascialeoni.com"},{"label":"Libri","link":"https:\/\/www.mascialeoni.com\/index.php\/category\/libri"},{"label":"Regalo della Grecia","link":"https:\/\/www.mascialeoni.com\/index.php\/2024\/09\/14\/regalo-della-grecia\/2004"}],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9ENO6-wk","_links":{"self":[{"href":"https:\/\/www.mascialeoni.com\/index.php\/wp-json\/wp\/v2\/posts\/2004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mascialeoni.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mascialeoni.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mascialeoni.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mascialeoni.com\/index.php\/wp-json\/wp\/v2\/comments?post=2004"}],"version-history":[{"count":6,"href":"https:\/\/www.mascialeoni.com\/index.php\/wp-json\/wp\/v2\/posts\/2004\/revisions"}],"predecessor-version":[{"id":2025,"href":"https:\/\/www.mascialeoni.com\/index.php\/wp-json\/wp\/v2\/posts\/2004\/revisions\/2025"}],"wp:attachment":[{"href":"https:\/\/www.mascialeoni.com\/index.php\/wp-json\/wp\/v2\/media?parent=2004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mascialeoni.com\/index.php\/wp-json\/wp\/v2\/categories?post=2004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mascialeoni.com\/index.php\/wp-json\/wp\/v2\/tags?post=2004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}